{"id":2387,"date":"2017-06-29T18:00:01","date_gmt":"2017-06-29T16:00:01","guid":{"rendered":"http:\/\/www.all-about-schmitz.de\/wordpress\/?p=2387"},"modified":"2018-09-13T11:52:12","modified_gmt":"2018-09-13T09:52:12","slug":"im-hoellenloch-auf-fabis-spuren","status":"publish","type":"post","link":"https:\/\/www.all-about-schmitz.de\/wordpress\/blog\/im-hoellenloch-auf-fabis-spuren\/","title":{"rendered":"Im H\u00f6llenloch &#8211; Auf Fabis Spuren"},"content":{"rendered":"<p>Man will ja was zu erz\u00e4hlen haben: Fabi zum Beispiel, ein Kollege von Beate, war vor zwei Jahren hier in Tallinn und erz\u00e4hlte von einem leerstehenden, ziemlich gruseligen Gef\u00e4ngnis namens Patarei.<\/p>\n<p>Das Gef\u00e4ngnis sei zwar verschlossen, aber man k\u00e4me durch ein Eisentor gut hinein. Tats\u00e4chlich wei\u00dft auch der Reisef\u00fchrer darauf hin, dass man sich ganz legal dort umsehen k\u00f6nne. Per WhatsApp schickte Fabi mir gestern sogar ein Bild, wo der Eingang zu finden sei. Und innen drin w\u00e4re es wirklich gruselig, durch die verlassenen R\u00e4ume zu gehen. Und verlaufen habe er sich damals auch.<\/p>\n<figure id=\"attachment_2391\" aria-describedby=\"caption-attachment-2391\" style=\"width: 600px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2391\" src=\"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/IMG_8194-600x418.jpg\" alt=\"\" width=\"600\" height=\"418\" srcset=\"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/IMG_8194-600x418.jpg 600w, https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/IMG_8194-768x535.jpg 768w, https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/IMG_8194-1024x713.jpg 1024w, https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/IMG_8194-388x270.jpg 388w, https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/IMG_8194.jpg 1242w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-2391\" class=\"wp-caption-text\">Das Gef\u00e4ngnis Patarei mit Fabis Hinweis, wo der Eingang zu finden sei.<\/figcaption><\/figure>\n<p>Die Geschichte der vier Hektar gro\u00dfen Trutzburg ist noch d\u00fcster als Fabis Erz\u00e4hlungen: Als Festung erbaut in der Zeit, als Estland zu Russland geh\u00f6rte, wurde Patarei in den Jahren des estnischen Unabh\u00e4ngigkeitskrieges von 1918 bis 1920 zum ersten Mal als Gef\u00e4ngnis genutzt. Ab 1941 war es f\u00fcr 4 Jahre Arbeits- und KZ-Lager der Nazis, danach Sowjet-Gef\u00e4ngnis und nach Losl\u00f6sung des Landes von der Sowjetunion 1991 noch elf Jahre estnische Haftanstalt.<\/p>\n<p>In Sowjetzeiten waren zeitweilig 5.000 Menschen auf dem Gel\u00e4nde untergebracht. Sie wurden f\u00fcr Wochen oder Monate in Zellen ohne Tageslicht eingekerkert. Die meisten von ihnen verschwanden dann in sibirischen Gulags. In einer 16-Mann-Zelle hausten bis zu 40 Gefangene.<\/p>\n<p>Wie viele Menschen im Gef\u00e4ngnis Patarei ums Leben kamen, wei\u00df niemand so genau. Fest steht: Von 878 aus Frankreich w\u00e4hrend des zweiten Weltkriegs deportierten Juden \u00fcberlebten nur 22 das H\u00f6llenloch, wie es die Einheimischen hier in Tallinn nennen.<\/p>\n<p>Trotz oder vielleicht sogar wegen all diesen Grauens klang ein Besuch des Patarei nach guten Idee. Denn Tallinn selber, genauer die Altstadt, ist zwar wunderh\u00fcbsch, aufger\u00e4umt, sauber und \u00fcbersichtlich, doch im Grunde so etwas wie eine Mischung aus T\u00fcbingen und Rothenburg &#8211; nur mit M\u00f6wen.<\/p>\n<p>Au\u00dferdem wird die Altstadt ein wenig auf Mittelalter getrimmt. Das macht aus Marketing-Gesichtspunkten durchaus Sinn. Doch das Mittelalter geht sowohl Beate als auch mir nicht nur am Allerwertesten, sondern an allen K\u00f6rperteilen vorbei.<\/p>\n<p>Den 30-min\u00fctigen Weg nach Patarei legen wir am Vormittag von unserem Hotel aus bei strahlendem Sonnenschein zu Fu\u00df zur\u00fcck.<\/p>\n<p><strong>Sicherheitskr\u00e4fte, \u00fcberall Sicherheitskr\u00e4fte<\/strong><\/p>\n<p>Auf halber Strecke begegnen sie uns dann das erste Mal. Sicherheitskr\u00e4fte, im klassischen Look, wie im Comic. Fette schwarze Karren, schwarze Anz\u00fcge, schwarze Krawatten, wei\u00dfe Hemden, Sonnenbrillen. Dazu ist die eine oder andere Stra\u00dfe gesperrt. Wir spekulieren, was wohl los sein mag.<\/p>\n<p>Egal, weiter Richtung Patarei. Kurz bevor ich den von Fabi eingezeichneten Weg einschlage, setzt sich Beate die Sonne genie\u00dfend auf eine Parkbank und will auf mich warten. Ich finde das von Fabi beschriebenen gro\u00dfe Eisentor schnell. Leider stehen zwei Sicherheitskr\u00e4fte davor, die mich nicht rein lassen.<\/p>\n<p>Gleich neben dem vermeintlichen Eingang beginnt eine gro\u00dfe Baustelle. Der hintere linke Teil des Gef\u00e4ngnisses wird abgerissen sowie das Geb\u00e4ude davor. Weil ich keine Lust habe so schnell aufzugeben, warte ich den Moment ab, in dem die Sicherheitskr\u00e4fte weggucken, klettere schnell \u00fcber den Bauzaun, achte darauf, dass mich kein Bauarbeiter sieht, husche \u00fcber die Baustelle auf das Gel\u00e4nde des ehemaligen Gef\u00e4ngnisses. Geht doch!<\/p>\n<p>Die meisten T\u00fcren im Geb\u00e4ude im inneren Bereich sind abgeschlossen (s. Titelbild). Doch nach einer Weile finde ich eine offene. In einem Raum liegen unz\u00e4hlige Spritzen und Infusionsschl\u00e4uche wild durcheinander. An den W\u00e4nden br\u00f6ckelt der Putz und der Schimmel bildet Blumenmuster. Gleich daneben ein Duschraum. Wandfarbe h\u00e4ngt in Fetzen herunter. Zwei Seiten sind noch mit hellgr\u00fcnen Kacheln \u00fcberzogen. Schon nach wenigen Augenblicken steht f\u00fcr mich fest: Das ist hier die ideale Kulisse f\u00fcr einen Horrorfilm.<\/p>\n<figure id=\"attachment_2388\" aria-describedby=\"caption-attachment-2388\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2388 size-medium\" src=\"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/1-600x800.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/1-600x800.jpg 600w, https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/1-768x1024.jpg 768w, https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/1-585x780.jpg 585w, https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/1-576x768.jpg 576w, https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/1-203x270.jpg 203w, https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/1.jpg 900w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-2388\" class=\"wp-caption-text\">Creepy: Unz\u00e4hlige Spritzen mit Infusionsschl\u00e4uchen.<\/figcaption><\/figure>\n<p>Etwas weiter ein bestenfalls 1,5 m breiter Gang mit zahlreichen offenen Zellent\u00fcren links und rechts. Ein-Mann-Zellen, in denen man sich kaum ausgestreckt hinlegen konnte ohne Tageslicht. Ich versuche mir auszumalen, wie es hier f\u00fcr einen Gefangenen gewesen sein muss. Die Luft ist feuchtkalt und irgendwie riecht es nicht sonderlich gut. Da h\u00f6re ich es knirschen. Jemand kommt den Gang entlang. Sch&#8230; Noch mehr Touristen auf Gruseltour? Die Seelen der Verstorbenen?<\/p>\n<p>&#8222;Hello&#8220; schallt es fragend durch den Gang? Und noch mal &#8222;Hello?&#8220; Da es ziemlich sinnlos ist, sich in einer bestenfalls 1,60 m langen, 2 m hohen und v\u00f6llig kahlen Gef\u00e4ngniszelle verstecken zu wollen, entscheide ich mich, mit einem freundlichen L\u00e4cheln den Raum zu verlassen und auf den Gang zu treten.<\/p>\n<p><strong>Was zum Teufel wollen die hier?<\/strong><\/p>\n<p>Sicherheitskr\u00e4fte. Zwei Mann. Ich fasse es nicht! Was zum Teufel wollen die hier? Auf jeden Fall bitten sie mich ebenso freundlich wie bestimmt, das Gel\u00e4nde zu verlassen und geleiten mich hinaus. Warum sie hier sind? Das kriege ich nicht aus ihnen heraus. Immerhin, im Gegensatz zu Fabi habe ich mich hier nicht verlaufen.<\/p>\n<p>Nach einer kurzen Weile treffe ich wieder auf Beate. Wir entscheiden uns, ein nahegelegenes Museum\u00a0\u00fcber die estnische Seefahrts- und Milit\u00e4rgeschichte zu besuchen. Nachdem wir uns im ersten Teil ausreichend \u00fcber die gro\u00dfe weite Welt der Seebojen informiert f\u00fchlen, gelangen wir zum H\u00f6hepunkt der Ausstellung: Das WW II U-Boot Lembit mit seinen 600 Tonnen. Wir waren tats\u00e4chlich beide noch nie in einem U-Boot und staunen nicht schlecht.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2390 aligncenter\" src=\"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/IMG_8158-e1498748802908-600x800.jpg\" alt=\"\" width=\"600\" height=\"800\" srcset=\"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/IMG_8158-e1498748802908-600x800.jpg 600w, https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/IMG_8158-e1498748802908-768x1024.jpg 768w, https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/IMG_8158-e1498748802908-585x780.jpg 585w, https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/IMG_8158-e1498748802908-576x768.jpg 576w, https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/IMG_8158-e1498748802908-203x270.jpg 203w, https:\/\/www.all-about-schmitz.de\/wordpress\/wp-content\/uploads\/2017\/06\/IMG_8158-e1498748802908.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>Danach noch etwas auf der Museumsterrasse die Sonne genie\u00dfen und dann langsam wieder zur\u00fcck. Von den Sicherheitskr\u00e4ften, die vorher hier \u00fcberall rumschwirrten, keine Spur mehr.<\/p>\n<p>Wir gehen in eine kleine Seitenstra\u00dfe, die an einer Au\u00dfenmauer des Patarei endet. Gleich daneben ein gr\u00f6\u00dferer Gedenkstein, der auf die 878 aus Frankreich stammenden Juden erinnert, die hier eingekerkert waren. Und zu Fu\u00dfe des Gedenksteins zwei frische Kr\u00e4nze. Wei\u00dfe Rosen mit zwei Sch\u00e4rpen in blau-wei\u00df-rot, der franz\u00f6sischen Flagge. Auf einer Sch\u00e4rpe steht in goldenen Lettern &#8222;Le Premier ministre de la Republique francaise&#8220;.<\/p>\n<p>Ein Griff zum Handy &#8230; ein Blick ins Internet &#8230; eben hat Edouard Philippe, der neue franz\u00f6sische Premierminister hier die beiden Kr\u00e4nze niedergelegt. Deshalb also die ganzen Sicherheitskr\u00e4fte.<\/p>\n<p>Immerhin, zumindest zwei von ihnen werden heute auch etwas zu erz\u00e4hlen haben. Denn, um Beate zu zitieren, &#8222;die haben ganz sicher noch nie so einen alten Sack wie dich aus dem Patarei geschmissen.&#8220; :-)<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Man will ja was zu erz\u00e4hlen haben: Fabi zum Beispiel, ein Kollege von Beate, war vor zwei Jahren hier in Tallinn und erz\u00e4hlte von einem leerstehenden, ziemlich gruseligen Gef\u00e4ngnis namens Patarei. Das Gef\u00e4ngnis sei zwar verschlossen, aber man k\u00e4me durch ein Eisentor gut hinein. Tats\u00e4chlich wei\u00dft auch der Reisef\u00fchrer darauf hin, dass man sich ganz &hellip; <\/p>\n<p class=\"read-more\"><a class=\"readmore-btn\" href=\"https:\/\/www.all-about-schmitz.de\/wordpress\/blog\/im-hoellenloch-auf-fabis-spuren\/\"><span>Read Article<\/span><span class=\"screen-reader-text\">  Read More<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":2389,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[299,300,75],"tags":[306,303,304,305,307,308,282],"class_list":["post-2387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baltikum","category-estland","category-reise","tag-gefaengnis","tag-lembit","tag-lennusadam","tag-patarei","tag-philippe","tag-premierminister","tag-tallinn"],"_links":{"self":[{"href":"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-json\/wp\/v2\/posts\/2387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-json\/wp\/v2\/comments?post=2387"}],"version-history":[{"count":9,"href":"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-json\/wp\/v2\/posts\/2387\/revisions"}],"predecessor-version":[{"id":2400,"href":"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-json\/wp\/v2\/posts\/2387\/revisions\/2400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-json\/wp\/v2\/media\/2389"}],"wp:attachment":[{"href":"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-json\/wp\/v2\/media?parent=2387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-json\/wp\/v2\/categories?post=2387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.all-about-schmitz.de\/wordpress\/wp-json\/wp\/v2\/tags?post=2387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}